{"id":130,"date":"2016-09-29T00:47:51","date_gmt":"2016-09-29T00:47:51","guid":{"rendered":"http:\/\/33ppp.de\/letsgoonajourney\/?p=130"},"modified":"2016-09-29T00:48:26","modified_gmt":"2016-09-29T00:48:26","slug":"was-ich-seit-ich-hier-bin-mehr-zu-schaetzen-gelernt-habe","status":"publish","type":"post","link":"https:\/\/33ppp.de\/letsgoonajourney\/2016\/09\/29\/was-ich-seit-ich-hier-bin-mehr-zu-schaetzen-gelernt-habe\/","title":{"rendered":"Was ich, seit ich hier bin, mehr zu sch\u00e4tzen gelernt habe\u2026"},"content":{"rendered":"<p><a href=\"http:\/\/twitter.com\/share?url=https%3A%2F%2F33ppp.de%2Fletsgoonajourney%2F2016%2F09%2F29%2Fwas-ich-seit-ich-hier-bin-mehr-zu-schaetzen-gelernt-habe%2F&amp;count=none&amp;text=Was ich, seit ich hier bin, mehr zu sch\u00e4tzen gelernt habe\u2026 - Let&#039;s go on a Journey\" class=\"twitter-share-button\">Tweet<\/a><\/p><p><span lang=\"DE\"><span style=\"color: #000000;font-family: Calibri\">Eine der wichtigsten Dinge die ich f\u00fcr mich erkennen musste seit ich hier bin, ist, dass eines der wichtigsten Werkzeuge die der Mensch besitzt seine Sprache ist. Zuvor war das, wie wahrscheinlich f\u00fcr so gut wie jeden, etwas Selbstverst\u00e4ndliches, aber wenn du an einem Punkt bist, indem du dich verst\u00e4ndigen, dich mitteilen, dich aufregen oder dich wirklich freuen willst und dir die Worte daf\u00fcr fehlen, das ist meiner Meinung nach ein schreckliches Gef\u00fchl. <\/span><\/span><\/p>\n<p><span lang=\"DE\"><span style=\"color: #000000;font-family: Calibri\">Die zweite Sache, sind meine Familie und Freunde. Es ist nicht so, dass ich hier alleine bin, aber in manchen Moment macht es mich tief traurig, wenn ich keinen verr\u00fcckten Bruder habe, mit dem ich mitten in der Nacht umherfahren kann und Unsinn machen kann oder einfach reden kann oder eine Mama, die wenn du mal wieder alles verplant hast, f\u00fcr dich da ist und dir hilft alles zu regeln oder eine beste Freundin, die einfach jede Verr\u00fccktheit mitmacht, mir jeden Tag neue Geschichten fast wie aus einen Film pr\u00e4sentiert und einfach genauso verr\u00fcckt ist wie du, oder die Momente wenn man einfach mal Menschen um sich haben will, die einen gl\u00fccklich machen und f\u00fcr einen da sind. <\/span><\/span><\/p>\n<p><span lang=\"DE\"><span style=\"color: #000000;font-family: Calibri\">Die n\u00e4chste Sache ist die deutsche Autoversicherung. Mehr dazu im n\u00e4chsten Beitrag, aber so viel sei gesagt, seid froh, dass ihr in Deutschland wohnt :D. <\/span><\/span><\/p>\n<p><span lang=\"DE\"><span style=\"color: #000000;font-family: Calibri\">Diese Liste werde ich \u00fcber das Jahr wahrscheinlich des \u00d6fteren mal erg\u00e4nzen. <\/span><\/span><\/p>\n<p><span lang=\"DE\"><span style=\"color: #000000;font-family: Calibri\">Bis dahin. Tschuss. Und an die Leute aus unser Whats app Gruppe, die das lesen, HAB EUCH LIEB. &lt;3<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TweetEine der wichtigsten Dinge die ich f\u00fcr mich erkennen musste seit ich hier bin, ist, dass eines der wichtigsten Werkzeuge die der Mensch besitzt seine Sprache ist. Zuvor war das, wie wahrscheinlich f\u00fcr so gut wie jeden, etwas Selbstverst\u00e4ndliches, aber wenn du an einem Punkt bist, indem du dich verst\u00e4ndigen, dich mitteilen, dich aufregen oder dich wirklich freuen willst und dir die Worte daf\u00fcr fehlen, das ist meiner Meinung nach ein schreckliches Gef\u00fchl. Die zweite Sache, sind meine Familie und&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/33ppp.de\/letsgoonajourney\/2016\/09\/29\/was-ich-seit-ich-hier-bin-mehr-zu-schaetzen-gelernt-habe\/\">Weiterlesen<span class=\"screen-reader-text\"> Weiterlesen<\/span><\/a><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-130","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/33ppp.de\/letsgoonajourney\/wp-json\/wp\/v2\/posts\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/33ppp.de\/letsgoonajourney\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/33ppp.de\/letsgoonajourney\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/33ppp.de\/letsgoonajourney\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/33ppp.de\/letsgoonajourney\/wp-json\/wp\/v2\/comments?post=130"}],"version-history":[{"count":2,"href":"https:\/\/33ppp.de\/letsgoonajourney\/wp-json\/wp\/v2\/posts\/130\/revisions"}],"predecessor-version":[{"id":132,"href":"https:\/\/33ppp.de\/letsgoonajourney\/wp-json\/wp\/v2\/posts\/130\/revisions\/132"}],"wp:attachment":[{"href":"https:\/\/33ppp.de\/letsgoonajourney\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/33ppp.de\/letsgoonajourney\/wp-json\/wp\/v2\/categories?post=130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/33ppp.de\/letsgoonajourney\/wp-json\/wp\/v2\/tags?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}